{"id":4381,"date":"2021-05-06T01:39:00","date_gmt":"2021-05-06T01:39:00","guid":{"rendered":"https:\/\/amacosi.omelet.pe\/?post_type=product&#038;p=4381"},"modified":"2025-10-08T16:55:41","modified_gmt":"2025-10-08T16:55:41","slug":"anhanger-kolibri","status":"publish","type":"product","link":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/","title":{"rendered":"Anh\u00e4nger Kolibri"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Dieses besondere Anh\u00e4ngerdesign pr\u00e4sentiert einen Kolibri. Diese wundersch\u00f6ne Vogelart ist bekannt als schwirrender, bienenflei\u00dfiger Nektarsammler und Meister des Gesangs. Kolibris wurden von der Inkas verehrt. Dieser exklusive Anh\u00e4nger ist eine handgemachte <br \/>einzigartige Kombination aus peruanischem 950er Silber und traditionellen Inkamaterialen wie Natursteinen, Meeresmuscheln und Perlmutt. <\/p>\n<p>Verleihen Sie Ihrem Outfit mit einem Schmuckst\u00fcck einen einzigartigen Stil. <\/p>\n<p>H\u00f6he: 5,5 cm <br \/>Breite: 5cm <\/p>\n<p>Handgemachter Echtsilber-Anh\u00e4nger mit Intarsien aus Natursteinen wie peruanischer T\u00fcrkis, Spondylus-Meeresmuscheln in den Farbt\u00f6nen lila, orange und rot sowie gelber und wei\u00dfer Perlmutt.<\/p>","protected":false},"featured_media":4384,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false},"product_brand":[],"product_cat":[71],"product_tag":[],"class_list":["post-4381","product","type-product","status-publish","has-post-thumbnail","product_cat-anhanger","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dieses besondere Anh\u00e4ngerdesign pr\u00e4sentiert einen Kolibri. Diese wundersch\u00f6ne Vogelart ist bekannt als schwirrender, bienenflei\u00dfiger Nektarsammler und Meister des Gesangs. Kolibris wurden von der Inkas verehrt. Dieser exklusive Anh\u00e4nger ist eine handgemachte einzigartige Kombination aus peruanischem 950er Silber und traditionellen Inkamaterialen wie Natursteinen, Meeresmuscheln und Perlmutt. Verleihen Sie Ihrem Outfit mit einem Schmuckst\u00fcck einen einzigartigen Stil. H\u00f6he: 5,5 cm Breite: 5cm Handgemachter Echtsilber-Anh\u00e4nger mit Intarsien aus Natursteinen wie peruanischer T\u00fcrkis, Spondylus-Meeresmuscheln in den Farbt\u00f6nen lila, orange und rot sowie gelber und wei\u00dfer Perlmutt.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"itesGeTF9eM6JekK4roXOlVeMmpLEN7z4zE6ZI760U4\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Amacosi | Schmuck - Kunst - Design\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Anh\u00e4nger Kolibri\" \/>\n\t\t<meta property=\"og:description\" content=\"Dieses besondere Anh\u00e4ngerdesign pr\u00e4sentiert einen Kolibri. Diese wundersch\u00f6ne Vogelart ist bekannt als schwirrender, bienenflei\u00dfiger Nektarsammler und Meister des Gesangs. Kolibris wurden von der Inkas verehrt. Dieser exklusive Anh\u00e4nger ist eine handgemachte einzigartige Kombination aus peruanischem 950er Silber und traditionellen Inkamaterialen wie Natursteinen, Meeresmuscheln und Perlmutt. Verleihen Sie Ihrem Outfit mit einem Schmuckst\u00fcck einen einzigartigen Stil. H\u00f6he: 5,5 cm Breite: 5cm Handgemachter Echtsilber-Anh\u00e4nger mit Intarsien aus Natursteinen wie peruanischer T\u00fcrkis, Spondylus-Meeresmuscheln in den Farbt\u00f6nen lila, orange und rot sowie gelber und wei\u00dfer Perlmutt.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/amacosi.de\/wp-content\/uploads\/2022\/02\/3Recurso-1.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/amacosi.de\/wp-content\/uploads\/2022\/02\/3Recurso-1.svg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"411\" \/>\n\t\t<meta property=\"og:image:height\" content=\"214\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-05-06T01:39:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-08T16:55:41+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amacosi.peruanischeschmuck\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Anh\u00e4nger Kolibri\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dieses besondere Anh\u00e4ngerdesign pr\u00e4sentiert einen Kolibri. Diese wundersch\u00f6ne Vogelart ist bekannt als schwirrender, bienenflei\u00dfiger Nektarsammler und Meister des Gesangs. Kolibris wurden von der Inkas verehrt. Dieser exklusive Anh\u00e4nger ist eine handgemachte einzigartige Kombination aus peruanischem 950er Silber und traditionellen Inkamaterialen wie Natursteinen, Meeresmuscheln und Perlmutt. Verleihen Sie Ihrem Outfit mit einem Schmuckst\u00fcck einen einzigartigen Stil. H\u00f6he: 5,5 cm Breite: 5cm Handgemachter Echtsilber-Anh\u00e4nger mit Intarsien aus Natursteinen wie peruanischer T\u00fcrkis, Spondylus-Meeresmuscheln in den Farbt\u00f6nen lila, orange und rot sowie gelber und wei\u00dfer Perlmutt.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/amacosi.de\/wp-content\/uploads\/2022\/02\/3Recurso-1.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/amacosi.de\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/amacosi.de\\\/en\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/categoria-producto\\\/silberschmuck\\\/#listItem\",\"name\":\"Silberschmuck\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/categoria-producto\\\/silberschmuck\\\/#listItem\",\"position\":3,\"name\":\"Silberschmuck\",\"item\":\"https:\\\/\\\/amacosi.de\\\/en\\\/categoria-producto\\\/silberschmuck\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/categoria-producto\\\/silberschmuck\\\/anhanger\\\/#listItem\",\"name\":\"Anh\\u00e4nger\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/categoria-producto\\\/silberschmuck\\\/anhanger\\\/#listItem\",\"position\":4,\"name\":\"Anh\\u00e4nger\",\"item\":\"https:\\\/\\\/amacosi.de\\\/en\\\/categoria-producto\\\/silberschmuck\\\/anhanger\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/#listItem\",\"name\":\"Anh\\u00e4nger Kolibri\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/categoria-producto\\\/silberschmuck\\\/#listItem\",\"name\":\"Silberschmuck\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/#listItem\",\"position\":5,\"name\":\"Anh\\u00e4nger Kolibri\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/categoria-producto\\\/silberschmuck\\\/anhanger\\\/#listItem\",\"name\":\"Anh\\u00e4nger\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/#itempage\",\"url\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/\",\"name\":\"Anh\\u00e4nger Kolibri\",\"description\":\"Dieses besondere Anh\\u00e4ngerdesign pr\\u00e4sentiert einen Kolibri. Diese wundersch\\u00f6ne Vogelart ist bekannt als schwirrender, bienenflei\\u00dfiger Nektarsammler und Meister des Gesangs. Kolibris wurden von der Inkas verehrt. Dieser exklusive Anh\\u00e4nger ist eine handgemachte einzigartige Kombination aus peruanischem 950er Silber und traditionellen Inkamaterialen wie Natursteinen, Meeresmuscheln und Perlmutt. Verleihen Sie Ihrem Outfit mit einem Schmuckst\\u00fcck einen einzigartigen Stil. H\\u00f6he: 5,5 cm Breite: 5cm Handgemachter Echtsilber-Anh\\u00e4nger mit Intarsien aus Natursteinen wie peruanischer T\\u00fcrkis, Spondylus-Meeresmuscheln in den Farbt\\u00f6nen lila, orange und rot sowie gelber und wei\\u00dfer Perlmutt.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/amacosi.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/370A0643-Bearbeitet.jpg\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/#mainImage\",\"width\":500,\"height\":500},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/#mainImage\"},\"datePublished\":\"2021-05-06T01:39:00+00:00\",\"dateModified\":\"2025-10-08T16:55:41+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/#organization\",\"name\":\"Amacosi\",\"description\":\"Schmuck - Kunst - Design Amacosi verbindet peruanische Tradition mit modernem Design. Seit 2015 entstehen handgefertigter Silberschmuck, nachhaltige Alpakamode und Kunsthandwerk \\u2013 fair produziert in Peru.\",\"url\":\"https:\\\/\\\/amacosi.de\\\/en\\\/\",\"email\":\"info@amacosi.de\",\"telephone\":\"+491729303504\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/amacosi.de\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/3Recurso-1.svg\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/#organizationLogo\",\"width\":411,\"height\":214},\"image\":{\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/producto\\\/anhanger-kolibri\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amacosi.peruanischeschmuck\",\"https:\\\/\\\/www.instagram.com\\\/amacosi.de\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/amacosi.de\\\/en\\\/\",\"name\":\"Amacosi\",\"description\":\"Schmuck - Kunst - Design\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/amacosi.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Anh\u00e4nger Kolibri","description":"Dieses besondere Anh\u00e4ngerdesign pr\u00e4sentiert einen Kolibri. Diese wundersch\u00f6ne Vogelart ist bekannt als schwirrender, bienenflei\u00dfiger Nektarsammler und Meister des Gesangs. Kolibris wurden von der Inkas verehrt. Dieser exklusive Anh\u00e4nger ist eine handgemachte einzigartige Kombination aus peruanischem 950er Silber und traditionellen Inkamaterialen wie Natursteinen, Meeresmuscheln und Perlmutt. Verleihen Sie Ihrem Outfit mit einem Schmuckst\u00fcck einen einzigartigen Stil. H\u00f6he: 5,5 cm Breite: 5cm Handgemachter Echtsilber-Anh\u00e4nger mit Intarsien aus Natursteinen wie peruanischer T\u00fcrkis, Spondylus-Meeresmuscheln in den Farbt\u00f6nen lila, orange und rot sowie gelber und wei\u00dfer Perlmutt.","canonical_url":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"itesGeTF9eM6JekK4roXOlVeMmpLEN7z4zE6ZI760U4","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en#listItem","position":1,"name":"Home","item":"https:\/\/amacosi.de\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/tienda\/#listItem","position":2,"name":"Tienda","item":"https:\/\/amacosi.de\/en\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/#listItem","name":"Silberschmuck"},"previousItem":{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/#listItem","position":3,"name":"Silberschmuck","item":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/","nextItem":{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/anhanger\/#listItem","name":"Anh\u00e4nger"},"previousItem":{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/anhanger\/#listItem","position":4,"name":"Anh\u00e4nger","item":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/anhanger\/","nextItem":{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/#listItem","name":"Anh\u00e4nger Kolibri"},"previousItem":{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/#listItem","name":"Silberschmuck"}},{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/#listItem","position":5,"name":"Anh\u00e4nger Kolibri","previousItem":{"@type":"ListItem","@id":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/anhanger\/#listItem","name":"Anh\u00e4nger"}}]},{"@type":"ItemPage","@id":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/#itempage","url":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/","name":"Anh\u00e4nger Kolibri","description":"Dieses besondere Anh\u00e4ngerdesign pr\u00e4sentiert einen Kolibri. Diese wundersch\u00f6ne Vogelart ist bekannt als schwirrender, bienenflei\u00dfiger Nektarsammler und Meister des Gesangs. Kolibris wurden von der Inkas verehrt. Dieser exklusive Anh\u00e4nger ist eine handgemachte einzigartige Kombination aus peruanischem 950er Silber und traditionellen Inkamaterialen wie Natursteinen, Meeresmuscheln und Perlmutt. Verleihen Sie Ihrem Outfit mit einem Schmuckst\u00fcck einen einzigartigen Stil. H\u00f6he: 5,5 cm Breite: 5cm Handgemachter Echtsilber-Anh\u00e4nger mit Intarsien aus Natursteinen wie peruanischer T\u00fcrkis, Spondylus-Meeresmuscheln in den Farbt\u00f6nen lila, orange und rot sowie gelber und wei\u00dfer Perlmutt.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/amacosi.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/amacosi.de\/wp-content\/uploads\/2021\/05\/370A0643-Bearbeitet.jpg","@id":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/#mainImage","width":500,"height":500},"primaryImageOfPage":{"@id":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/#mainImage"},"datePublished":"2021-05-06T01:39:00+00:00","dateModified":"2025-10-08T16:55:41+00:00"},{"@type":"Organization","@id":"https:\/\/amacosi.de\/en\/#organization","name":"Amacosi","description":"Schmuck - Kunst - Design Amacosi verbindet peruanische Tradition mit modernem Design. Seit 2015 entstehen handgefertigter Silberschmuck, nachhaltige Alpakamode und Kunsthandwerk \u2013 fair produziert in Peru.","url":"https:\/\/amacosi.de\/en\/","email":"info@amacosi.de","telephone":"+491729303504","logo":{"@type":"ImageObject","url":"https:\/\/amacosi.de\/wp-content\/uploads\/2022\/02\/3Recurso-1.svg","@id":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/#organizationLogo","width":411,"height":214},"image":{"@id":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/amacosi.peruanischeschmuck","https:\/\/www.instagram.com\/amacosi.de\/"]},{"@type":"WebSite","@id":"https:\/\/amacosi.de\/en\/#website","url":"https:\/\/amacosi.de\/en\/","name":"Amacosi","description":"Schmuck - Kunst - Design","inLanguage":"en-US","publisher":{"@id":"https:\/\/amacosi.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Amacosi | Schmuck - Kunst - Design","og:type":"article","og:title":"Anh\u00e4nger Kolibri","og:description":"Dieses besondere Anh\u00e4ngerdesign pr\u00e4sentiert einen Kolibri. Diese wundersch\u00f6ne Vogelart ist bekannt als schwirrender, bienenflei\u00dfiger Nektarsammler und Meister des Gesangs. Kolibris wurden von der Inkas verehrt. Dieser exklusive Anh\u00e4nger ist eine handgemachte einzigartige Kombination aus peruanischem 950er Silber und traditionellen Inkamaterialen wie Natursteinen, Meeresmuscheln und Perlmutt. Verleihen Sie Ihrem Outfit mit einem Schmuckst\u00fcck einen einzigartigen Stil. H\u00f6he: 5,5 cm Breite: 5cm Handgemachter Echtsilber-Anh\u00e4nger mit Intarsien aus Natursteinen wie peruanischer T\u00fcrkis, Spondylus-Meeresmuscheln in den Farbt\u00f6nen lila, orange und rot sowie gelber und wei\u00dfer Perlmutt.","og:url":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/","og:image":"https:\/\/amacosi.de\/wp-content\/uploads\/2022\/02\/3Recurso-1.svg","og:image:secure_url":"https:\/\/amacosi.de\/wp-content\/uploads\/2022\/02\/3Recurso-1.svg","og:image:width":411,"og:image:height":214,"article:published_time":"2021-05-06T01:39:00+00:00","article:modified_time":"2025-10-08T16:55:41+00:00","article:publisher":"https:\/\/www.facebook.com\/amacosi.peruanischeschmuck","twitter:card":"summary","twitter:title":"Anh\u00e4nger Kolibri","twitter:description":"Dieses besondere Anh\u00e4ngerdesign pr\u00e4sentiert einen Kolibri. Diese wundersch\u00f6ne Vogelart ist bekannt als schwirrender, bienenflei\u00dfiger Nektarsammler und Meister des Gesangs. Kolibris wurden von der Inkas verehrt. Dieser exklusive Anh\u00e4nger ist eine handgemachte einzigartige Kombination aus peruanischem 950er Silber und traditionellen Inkamaterialen wie Natursteinen, Meeresmuscheln und Perlmutt. Verleihen Sie Ihrem Outfit mit einem Schmuckst\u00fcck einen einzigartigen Stil. H\u00f6he: 5,5 cm Breite: 5cm Handgemachter Echtsilber-Anh\u00e4nger mit Intarsien aus Natursteinen wie peruanischer T\u00fcrkis, Spondylus-Meeresmuscheln in den Farbt\u00f6nen lila, orange und rot sowie gelber und wei\u00dfer Perlmutt.","twitter:image":"https:\/\/amacosi.de\/wp-content\/uploads\/2022\/02\/3Recurso-1.svg"},"aioseo_meta_data":{"post_id":"4381","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2022-05-10 18:45:41","updated":"2025-10-08 17:07:38","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/amacosi.de\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/amacosi.de\/en\/tienda\/\" title=\"Tienda\">Tienda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/\" title=\"Silberschmuck\">Silberschmuck<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/anhanger\/\" title=\"Anh\u00e4nger\">Anh\u00e4nger<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAnh\u00e4nger Kolibri\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/amacosi.de\/en"},{"label":"Tienda","link":"https:\/\/amacosi.de\/en\/tienda\/"},{"label":"Silberschmuck","link":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/"},{"label":"Anh\u00e4nger","link":"https:\/\/amacosi.de\/en\/categoria-producto\/silberschmuck\/anhanger\/"},{"label":"Anh\u00e4nger Kolibri","link":"https:\/\/amacosi.de\/en\/producto\/anhanger-kolibri\/"}],"_links":{"self":[{"href":"https:\/\/amacosi.de\/en\/wp-json\/wp\/v2\/product\/4381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amacosi.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amacosi.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amacosi.de\/en\/wp-json\/wp\/v2\/media\/4384"}],"wp:attachment":[{"href":"https:\/\/amacosi.de\/en\/wp-json\/wp\/v2\/media?parent=4381"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/amacosi.de\/en\/wp-json\/wp\/v2\/product_brand?post=4381"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amacosi.de\/en\/wp-json\/wp\/v2\/product_cat?post=4381"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amacosi.de\/en\/wp-json\/wp\/v2\/product_tag?post=4381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}